{"id":296,"count":5,"description":"","link":"https:\/\/www.mirest.com\/es\/tag\/ley-federal-del-trabajo\/","name":"Ley Federal del Trabajo","slug":"ley-federal-del-trabajo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mirest.com\/es\/wp-json\/wp\/v2\/tags\/296"}],"collection":[{"href":"https:\/\/www.mirest.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mirest.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mirest.com\/es\/wp-json\/wp\/v2\/posts?tags=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}